{"id":141,"date":"2006-02-04T21:34:32","date_gmt":"2006-02-04T19:34:32","guid":{"rendered":"http:\/\/www.dioptrin.de\/m\/hello\/?p=141"},"modified":"2006-02-04T21:34:32","modified_gmt":"2006-02-04T19:34:32","slug":"de-sandi-is-da-juchu","status":"publish","type":"post","link":"https:\/\/dioptrin.de\/m\/hello\/2006\/02\/de-sandi-is-da-juchu\/","title":{"rendered":"de sandi is da! (JUCHU)"},"content":{"rendered":"<p>da simmer also schon in cusco &#8211; total verr\u00fcckt!<br \/>\nnachdem sich die frau kessler mit schmerz- und migr\u00e4nemitteln und mit coca-toffees gegen h\u00f6henkrankheit pr\u00e4pariert hat, komm ich endlich dazu, mir einen t\u00fcrkisfarbenen poncho nebst kapuze von dem armen peruaner weben zu lassen, dem nach meiner fliessend spanischsprachigen pen\u00e4tranz (wie schreibt man das denn nu?) nix anderes \u00fcbrig blieb, als mir noch 5 soles rabatt zu geben! hach, ich bin ja so ne knallharte gesch\u00e4ftemacherin&#8230; nachdem unsere neue karriere als dvd-verk\u00e4uferinnen aufm limaer schwarzmarkt ein j\u00e4hes ende gefunden hatte, als der besitzer des h\u00fcbschen etablissements wiederkam und seinen laden pl\u00f6tzlich wieder f\u00fcr sich selbst beanspruchte (unversch\u00e4mtheit), muss ich ja irgendwie anders geld sparen!<br \/>\nheute abend hat sich der gute ponchoweber dann hoffentlich die finger wundgewebt und die olle pe kann dann bald in deutschland neue modetrends setten: tragt mehr ponchos!<br \/>\nunsere weiteren vorhaben f\u00fcr die n\u00e4chsten tage: machupicchu rocken und dann ab ins dschungelcamp (schliesslich sind wir mindestens G-promis!).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.dioptrin.de\/m\/hello\/wp-content\/dvdshop.jpg\" width=\"460\" height=\"345\" alt=\"dvd\" title=\"dvd\" \/><br \/>\nde m\u00e4dschengestalter folgen ihrer berufung<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.dioptrin.de\/m\/hello\/wp-content\/aussicht.jpg\" width=\"460\" height=\"345\" alt=\"aussicht\" title=\"aussicht\" \/><br \/>\ndekadenter blick von unserer hotel-terasse (zimmerpreis selbstverst\u00e4ndlich runtergehandelt)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.dioptrin.de\/m\/hello\/wp-content\/plaza.jpg\" width=\"460\" height=\"345\" alt=\"plaza\" title=\"plaza\" \/><br \/>\ncusco plaza<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.dioptrin.de\/m\/hello\/wp-content\/muddimauer.jpg\" width=\"460\" height=\"613\" alt=\"muddi\" title=\"muddi\" \/><br \/>\nmuddi an dor inka-mauer &#8211; wie authentisch (verr\u00fcckt)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.dioptrin.de\/m\/hello\/wp-content\/sanditreppe.jpg\" width=\"460\" height=\"613\" alt=\"sandi\" title=\"sandi\" \/><br \/>\nqueen of se vornehme bl\u00e4sse<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da simmer also schon in cusco &#8211; total verr\u00fcckt! nachdem sich die frau kessler mit schmerz- und migr\u00e4nemitteln und mit coca-toffees gegen h\u00f6henkrankheit pr\u00e4pariert hat, komm ich endlich dazu, mir einen t\u00fcrkisfarbenen poncho nebst kapuze von dem armen peruaner weben zu lassen, dem nach meiner fliessend spanischsprachigen pen\u00e4tranz (wie schreibt man das denn nu?) nix &hellip; <a href=\"https:\/\/dioptrin.de\/m\/hello\/2006\/02\/de-sandi-is-da-juchu\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">de sandi is da! (JUCHU)<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-141","post","type-post","status-publish","format-standard","hentry","category-bla"],"_links":{"self":[{"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/posts\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/comments?post=141"}],"version-history":[{"count":0,"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/posts\/141\/revisions"}],"wp:attachment":[{"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/media?parent=141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/categories?post=141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dioptrin.de\/m\/hello\/wp-json\/wp\/v2\/tags?post=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}